

{"id":13610,"date":"2025-03-11T06:15:00","date_gmt":"2025-03-11T06:15:00","guid":{"rendered":"https:\/\/www.in-magazines.com\/magazine\/?p=13610"},"modified":"2025-03-13T08:02:29","modified_gmt":"2025-03-13T08:02:29","slug":"valbonne-le-gymnase-des-bouillides-a-rouvert-ses-portes","status":"publish","type":"post","link":"https:\/\/www.in-magazines.com\/magazine\/sommaire\/inmagazine-40\/valbonne-le-gymnase-des-bouillides-a-rouvert-ses-portes\/","title":{"rendered":"VALBONNE: Le gymnase des Bouillides a rouvert ses portes"},"content":{"rendered":"\n<p>Ferm\u00e9 depuis septembre 2023 pour des travaux de r\u00e9novation, le gymnase des Bouillides a officiellement rouvert ses portes en d\u00e9but d\u2019ann\u00e9e. <\/p>\n\n\n\n<p>Les associations profitent d\u00e9sormais d\u2019un \u00e9quipement refait \u00e0 neuf : salle de danse et de sports, vestiaires, tribunes, cr\u00e9ation d\u2019un ascenseur, acc\u00e8s PMR\u2026 De nouveaux am\u00e9nagements qui assurent une meilleure isolation du b\u00e2timent en hiver et une ventilation optimale en \u00e9t\u00e9 gr\u00e2ce \u00e0 des ouvrants automatiques. L\u2019\u00e9quipement est un mod\u00e8le en mati\u00e8re de r\u00e9novation thermique avec pour objectif de r\u00e9duire de 58 % sa consommation \u00e9nerg\u00e9tique et sa consommation de gaz \u00e0 effet de serre de 78 % gr\u00e2ce notamment \u00e0 des pompes \u00e0 chaleur. La toiture se voit \u00e9galement \u00e9quiper de panneaux photovolta\u00efques, Montant de l\u2019op\u00e9ration : 4, 92 M\u20ac.<\/p>\n\n\n<a href=\"#\" class=\"_3d-flip-book  fb3d-link-lightbox-mode\" data-id=\"13375\" data-mode=\"link-lightbox\" data-title=\"false\" data-template=\"short-white-book-view\" data-lightbox=\"dark\" data-urlparam=\"fb3d-page\" data-page-n=\"0\" data-pdf=\"\" data-tax=\"null\" data-thumbnail=\"\" data-cols=\"3\" data-query=\"\"><img decoding=\"async\" src=\"http:\/\/www.in-magazines.com\/magazine\/wp-content\/uploads\/2021\/05\/btn.jpg\"><\/a>\n","protected":false},"excerpt":{"rendered":"<p>Ferm&eacute; depuis septembre 2023 pour des travaux de r&eacute;novation, le gymnase des Bouillides a officiellement rouvert ses portes en d&eacute;but d&rsquo;ann&eacute;e. Les associations profitent d&eacute;sormais d&rsquo;un &eacute;quipement refait &agrave; neuf : salle de danse et de sports, vestiaires, tribunes, cr&eacute;ation d&rsquo;un ascenseur, acc&egrave;s PMR&hellip; De nouveaux am&eacute;nagements qui assurent une meilleure isolation du b&acirc;timent en&hellip; <a class=\"more-link\" href=\"https:\/\/www.in-magazines.com\/magazine\/sommaire\/inmagazine-40\/valbonne-le-gymnase-des-bouillides-a-rouvert-ses-portes\/\">Poursuivre la lecture <span class=\"screen-reader-text\">VALBONNE: Le gymnase des Bouillides a rouvert ses portes<\/span><\/a><\/p>\n","protected":false},"author":1,"featured_media":13611,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2556,1697],"tags":[127,1202],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v16.2 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>VALBONNE: Le gymnase des Bouillides a rouvert ses portes - In Magazines<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/www.in-magazines.com\/magazine\/sommaire\/inmagazine-40\/valbonne-le-gymnase-des-bouillides-a-rouvert-ses-portes\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"VALBONNE: Le gymnase des Bouillides a rouvert ses portes - In Magazines\" \/>\n<meta property=\"og:description\" content=\"Ferm&eacute; depuis septembre 2023 pour des travaux de r&eacute;novation, le gymnase des Bouillides a officiellement rouvert ses portes en d&eacute;but d&rsquo;ann&eacute;e. Les associations profitent d&eacute;sormais d&rsquo;un &eacute;quipement refait &agrave; neuf : salle de danse et de sports, vestiaires, tribunes, cr&eacute;ation d&rsquo;un ascenseur, acc&egrave;s PMR&hellip; De nouveaux am&eacute;nagements qui assurent une meilleure isolation du b&acirc;timent en&hellip; Poursuivre la lecture VALBONNE: Le gymnase des Bouillides a rouvert ses portes\" \/>\n<meta property=\"og:url\" content=\"https:\/\/www.in-magazines.com\/magazine\/sommaire\/inmagazine-40\/valbonne-le-gymnase-des-bouillides-a-rouvert-ses-portes\/\" \/>\n<meta property=\"og:site_name\" content=\"In Magazines\" \/>\n<meta property=\"article:published_time\" content=\"2025-03-11T06:15:00+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2025-03-13T08:02:29+00:00\" \/>\n<meta property=\"og:image\" content=\"http:\/\/www.in-magazines.com\/magazine\/wp-content\/uploads\/2025\/03\/VALBONNE-Le-gymnase-des-Bouillides-a-rouvert-ses-portes-5.jpg\" \/>\n\t<meta property=\"og:image:width\" content=\"410\" \/>\n\t<meta property=\"og:image:height\" content=\"273\" \/>\n<meta name=\"twitter:label1\" content=\"Dur\u00e9e de lecture est.\">\n\t<meta name=\"twitter:data1\" content=\"1 minute\">\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"WebSite\",\"@id\":\"https:\/\/www.in-magazines.com\/magazine\/#website\",\"url\":\"https:\/\/www.in-magazines.com\/magazine\/\",\"name\":\"In Magazines\",\"description\":\"\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":\"https:\/\/www.in-magazines.com\/magazine\/?s={search_term_string}\",\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/www.in-magazines.com\/magazine\/sommaire\/inmagazine-40\/valbonne-le-gymnase-des-bouillides-a-rouvert-ses-portes\/#primaryimage\",\"inLanguage\":\"fr-FR\",\"url\":\"https:\/\/www.in-magazines.com\/magazine\/wp-content\/uploads\/2025\/03\/VALBONNE-Le-gymnase-des-Bouillides-a-rouvert-ses-portes-5.jpg\",\"contentUrl\":\"https:\/\/www.in-magazines.com\/magazine\/wp-content\/uploads\/2025\/03\/VALBONNE-Le-gymnase-des-Bouillides-a-rouvert-ses-portes-5.jpg\",\"width\":410,\"height\":273},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/www.in-magazines.com\/magazine\/sommaire\/inmagazine-40\/valbonne-le-gymnase-des-bouillides-a-rouvert-ses-portes\/#webpage\",\"url\":\"https:\/\/www.in-magazines.com\/magazine\/sommaire\/inmagazine-40\/valbonne-le-gymnase-des-bouillides-a-rouvert-ses-portes\/\",\"name\":\"VALBONNE: Le gymnase des Bouillides a rouvert ses portes - In Magazines\",\"isPartOf\":{\"@id\":\"https:\/\/www.in-magazines.com\/magazine\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/www.in-magazines.com\/magazine\/sommaire\/inmagazine-40\/valbonne-le-gymnase-des-bouillides-a-rouvert-ses-portes\/#primaryimage\"},\"datePublished\":\"2025-03-11T06:15:00+00:00\",\"dateModified\":\"2025-03-13T08:02:29+00:00\",\"author\":{\"@id\":\"https:\/\/www.in-magazines.com\/magazine\/#\/schema\/person\/c27e7dabb9a1ef380814bdd5636d07e3\"},\"breadcrumb\":{\"@id\":\"https:\/\/www.in-magazines.com\/magazine\/sommaire\/inmagazine-40\/valbonne-le-gymnase-des-bouillides-a-rouvert-ses-portes\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/www.in-magazines.com\/magazine\/sommaire\/inmagazine-40\/valbonne-le-gymnase-des-bouillides-a-rouvert-ses-portes\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/www.in-magazines.com\/magazine\/sommaire\/inmagazine-40\/valbonne-le-gymnase-des-bouillides-a-rouvert-ses-portes\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"item\":{\"@id\":\"https:\/\/www.in-magazines.com\/magazine\/sommaire\/inmagazine-40\/valbonne-le-gymnase-des-bouillides-a-rouvert-ses-portes\/#webpage\"}}]},{\"@type\":\"Person\",\"@id\":\"https:\/\/www.in-magazines.com\/magazine\/#\/schema\/person\/c27e7dabb9a1ef380814bdd5636d07e3\",\"name\":\"backinmag\",\"image\":{\"@type\":\"ImageObject\",\"@id\":\"https:\/\/www.in-magazines.com\/magazine\/#personlogo\",\"inLanguage\":\"fr-FR\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/13a234bb19dc4fd04793d73c3472fbdb?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/13a234bb19dc4fd04793d73c3472fbdb?s=96&d=mm&r=g\",\"caption\":\"backinmag\"},\"sameAs\":[\"http:\/\/www.in-magazines.com\/magazin\"]}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","_links":{"self":[{"href":"https:\/\/www.in-magazines.com\/magazine\/wp-json\/wp\/v2\/posts\/13610"}],"collection":[{"href":"https:\/\/www.in-magazines.com\/magazine\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.in-magazines.com\/magazine\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.in-magazines.com\/magazine\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.in-magazines.com\/magazine\/wp-json\/wp\/v2\/comments?post=13610"}],"version-history":[{"count":5,"href":"https:\/\/www.in-magazines.com\/magazine\/wp-json\/wp\/v2\/posts\/13610\/revisions"}],"predecessor-version":[{"id":13778,"href":"https:\/\/www.in-magazines.com\/magazine\/wp-json\/wp\/v2\/posts\/13610\/revisions\/13778"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.in-magazines.com\/magazine\/wp-json\/wp\/v2\/media\/13611"}],"wp:attachment":[{"href":"https:\/\/www.in-magazines.com\/magazine\/wp-json\/wp\/v2\/media?parent=13610"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.in-magazines.com\/magazine\/wp-json\/wp\/v2\/categories?post=13610"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.in-magazines.com\/magazine\/wp-json\/wp\/v2\/tags?post=13610"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}